{"id":1564,"date":"2017-01-27T11:04:46","date_gmt":"2017-01-27T10:04:46","guid":{"rendered":"http:\/\/www.bergvideomedia.de\/wpkp\/?p=1564"},"modified":"2020-11-07T17:14:19","modified_gmt":"2020-11-07T16:14:19","slug":"beispiel-14","status":"publish","type":"post","link":"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/","title":{"rendered":"Website\/Web-Video"},"content":{"rendered":"<h4 class=\"beitragstexte\">Website: Lonetal-Gastef\u00fchrer &#8211; Touren auf den Spuren der Eiszeitk\u00fcnstler zu den H\u00f6hlen der Steinzeitj\u00e4ger<\/h4>\n<h4 class=\"beitragstexte\">\n<a href=\"http:\/\/www.lonetaltour.de\" target=\"_blanc\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.bergvideomedia.de\/wpkp\/wp-content\/uploads\/2017\/01\/web_beispiel_14.jpg\" alt=\"website Ansicht\" width=\"640\" height=\"570\" class=\"aligncenter size-full wp-image-1565\" srcset=\"https:\/\/www.bergvideomedia.de\/wpkp\/wp-content\/uploads\/2017\/01\/web_beispiel_14.jpg 640w, https:\/\/www.bergvideomedia.de\/wpkp\/wp-content\/uploads\/2017\/01\/web_beispiel_14-300x267.jpg 300w, https:\/\/www.bergvideomedia.de\/wpkp\/wp-content\/uploads\/2017\/01\/web_beispiel_14-600x534.jpg 600w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>Zur G\u00e4stef\u00fchrer Website &#8222;Lonetaltour&#8220;<\/a><br \/>\n<\/h4>\n<h4 class=\"beitragstexte\">Gestaltung, Programmierung, Filmproduktion, Grafik, teilw. Fotografie.<\/h4>\n<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container align_center\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_3 us_custom_80a192e9\" href=\"https:\/\/www.bergvideomedia.de\/wpkp#examples\"><span class=\"w-btn-label\">Startseite<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Website: Lonetal-Gastef\u00fchrer &#8211; Touren auf den Spuren der Eiszeitk\u00fcnstler zu den H\u00f6hlen der Steinzeitj\u00e4ger Zur G\u00e4stef\u00fchrer Website &#8222;Lonetaltour&#8220; Gestaltung, Programmierung, Filmproduktion, Grafik, teilw. Fotografie.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-1564","post","type-post","status-publish","format-standard","hentry","category-beispiele"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Website\/Web-Video - Berg-VideoMedia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Website\/Web-Video - Berg-VideoMedia\" \/>\n<meta property=\"og:description\" content=\"Website: Lonetal-Gastef\u00fchrer &#8211; Touren auf den Spuren der Eiszeitk\u00fcnstler zu den H\u00f6hlen der Steinzeitj\u00e4ger Zur G\u00e4stef\u00fchrer Website &#8222;Lonetaltour&#8220; Gestaltung, Programmierung, Filmproduktion, Grafik, teilw. Fotografie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Berg-VideoMedia\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-27T10:04:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-07T16:14:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bergvideomedia.de\/wpkp\/wp-content\/uploads\/2017\/01\/web_beispiel_14.jpg\" \/>\n<meta name=\"author\" content=\"berg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"berg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/\",\"url\":\"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/\",\"name\":\"Website\/Web-Video - Berg-VideoMedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.bergvideomedia.de\/wpkp\/#website\"},\"datePublished\":\"2017-01-27T10:04:46+00:00\",\"dateModified\":\"2020-11-07T16:14:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.bergvideomedia.de\/wpkp\/#\/schema\/person\/8636844e16f053ac919e0da5df9876db\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.bergvideomedia.de\/wpkp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Website\/Web-Video\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bergvideomedia.de\/wpkp\/#website\",\"url\":\"https:\/\/www.bergvideomedia.de\/wpkp\/\",\"name\":\"Berg-VideoMedia\",\"description\":\"Medienproduktion - Langenau\/Ulm\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bergvideomedia.de\/wpkp\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bergvideomedia.de\/wpkp\/#\/schema\/person\/8636844e16f053ac919e0da5df9876db\",\"name\":\"berg\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.bergvideomedia.de\/wpkp\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a4f97da2bee91e2e067c0a79301ba62?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a4f97da2bee91e2e067c0a79301ba62?s=96&d=mm&r=g\",\"caption\":\"berg\"},\"url\":\"https:\/\/www.bergvideomedia.de\/wpkp\/author\/berg\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Website\/Web-Video - Berg-VideoMedia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/","og_locale":"de_DE","og_type":"article","og_title":"Website\/Web-Video - Berg-VideoMedia","og_description":"Website: Lonetal-Gastef\u00fchrer &#8211; Touren auf den Spuren der Eiszeitk\u00fcnstler zu den H\u00f6hlen der Steinzeitj\u00e4ger Zur G\u00e4stef\u00fchrer Website &#8222;Lonetaltour&#8220; Gestaltung, Programmierung, Filmproduktion, Grafik, teilw. Fotografie.","og_url":"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/","og_site_name":"Berg-VideoMedia","article_published_time":"2017-01-27T10:04:46+00:00","article_modified_time":"2020-11-07T16:14:19+00:00","og_image":[{"url":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-content\/uploads\/2017\/01\/web_beispiel_14.jpg"}],"author":"berg","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"berg"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/","url":"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/","name":"Website\/Web-Video - Berg-VideoMedia","isPartOf":{"@id":"https:\/\/www.bergvideomedia.de\/wpkp\/#website"},"datePublished":"2017-01-27T10:04:46+00:00","dateModified":"2020-11-07T16:14:19+00:00","author":{"@id":"https:\/\/www.bergvideomedia.de\/wpkp\/#\/schema\/person\/8636844e16f053ac919e0da5df9876db"},"breadcrumb":{"@id":"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bergvideomedia.de\/wpkp\/2017\/01\/27\/beispiel-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.bergvideomedia.de\/wpkp\/"},{"@type":"ListItem","position":2,"name":"Website\/Web-Video"}]},{"@type":"WebSite","@id":"https:\/\/www.bergvideomedia.de\/wpkp\/#website","url":"https:\/\/www.bergvideomedia.de\/wpkp\/","name":"Berg-VideoMedia","description":"Medienproduktion - Langenau\/Ulm","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bergvideomedia.de\/wpkp\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.bergvideomedia.de\/wpkp\/#\/schema\/person\/8636844e16f053ac919e0da5df9876db","name":"berg","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bergvideomedia.de\/wpkp\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a4f97da2bee91e2e067c0a79301ba62?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a4f97da2bee91e2e067c0a79301ba62?s=96&d=mm&r=g","caption":"berg"},"url":"https:\/\/www.bergvideomedia.de\/wpkp\/author\/berg\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-json\/wp\/v2\/posts\/1564"}],"collection":[{"href":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-json\/wp\/v2\/comments?post=1564"}],"version-history":[{"count":7,"href":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-json\/wp\/v2\/posts\/1564\/revisions"}],"predecessor-version":[{"id":2873,"href":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-json\/wp\/v2\/posts\/1564\/revisions\/2873"}],"wp:attachment":[{"href":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-json\/wp\/v2\/media?parent=1564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-json\/wp\/v2\/categories?post=1564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bergvideomedia.de\/wpkp\/wp-json\/wp\/v2\/tags?post=1564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}